{"id":280,"date":"2022-05-03T17:06:31","date_gmt":"2022-05-03T17:06:31","guid":{"rendered":"https:\/\/evolutio-ci.com\/?page_id=280"},"modified":"2023-12-22T09:22:43","modified_gmt":"2023-12-22T09:22:43","slug":"publicaciones-2","status":"publish","type":"page","link":"https:\/\/evolutio-ci.com\/index.php\/publicaciones-2\/","title":{"rendered":"Publicaciones"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbImagen del mundo azul\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#0F1154&#8243; overflow-x=\u00bbhidden\u00bb overflow-y=\u00bbhidden\u00bb custom_padding_tablet=\u00bb\u00bb custom_padding_phone=\u00bb||0px||false|false\u00bb background_horizontal_offset_tablet=\u00bb-25vw\u00bb collapsed=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; custom_padding_last_edited=\u00bbon|tablet\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb background_image=\u00bbhttp:\/\/evolutio-ci.com\/wp-content\/uploads\/2022\/05\/Financial-Firm-bg9b.png\u00bb parallax=\u00bbon\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb-1px|auto||auto||\u00bb custom_padding=\u00bb||||false|false\u00bb custom_padding_tablet=\u00bb||||false|false\u00bb custom_padding_phone=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbPerspectivas\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><a href=\"https:\/\/evolutio-ci.com\/index.php\/informes-y-notas\/\"><strong><span style=\"color: #ff9900;\">Publicaciones<\/span><\/strong><\/a><\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbNotas\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bbhttps:\/\/evolutio-ci.com\/index.php\/informes-y-notas\/\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><a href=\"https:\/\/evolutio-ci.com\/index.php\/informes-y-notas\/\"><span style=\"color: #ff9900;\"><strong>Notas<\/strong><\/span><\/a><\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbInformes\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bbhttps:\/\/evolutio-ci.com\/index.php\/informes-y-notas\/\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><a href=\"https:\/\/evolutio-ci.com\/index.php\/informes-y-notas\/\"><span style=\"color: #ff9900;\"><strong>Informes<\/strong><\/span><\/a><\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAn\u00e1lisis\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong><span style=\"color: #ff9900;\">An\u00e1lisis<\/span><\/strong><\/h2>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbMedios\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><a href=\"https:\/\/evolutio-ci.com\/index.php\/publicaciones\/\"><strong><span style=\"color: #ff9900;\">Medios<\/span><\/strong><\/a><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image title_text=\u00bbFinancial-Firm-bg9b\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#0F1154&#8243; custom_margin=\u00bb-2px|||||\u00bb saved_tabs=\u00bball\u00bb locked=\u00bboff\u00bb collapsed=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,1_4,1_2&#8243; _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb20px\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_social_media_follow_network social_network=\u00bblinkedin\u00bb url=\u00bbhttps:\/\/www.linkedin.com\/in\/pablo-de-vicente-hern%C3%A1ndez-58207115\/\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#007bb6&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding_tablet=\u00bb||||false|false\u00bb custom_padding_phone=\u00bb||||false|false\u00bb custom_padding_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.16.0&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbRoboto|500|||||||\u00bb text_text_color=\u00bb#000000&#8243; text_font_size=\u00bb18px\u00bb text_line_height=\u00bb180%\u00bb header_font=\u00bbMontserrat|700|||||||\u00bb header_text_color=\u00bb#0F1154&#8243; header_font_size=\u00bb125px\u00bb header_line_height=\u00bb110%\u00bb header_2_font=\u00bbMontserrat|600|||||||\u00bb header_2_text_color=\u00bb#0F1154&#8243; header_2_font_size=\u00bb70px\u00bb header_2_line_height=\u00bb120%\u00bb header_3_font=\u00bbMontserrat|600|||||||\u00bb header_3_text_color=\u00bb#FFFFFF\u00bb header_3_font_size=\u00bb40px\u00bb header_3_line_height=\u00bb140%\u00bb header_4_font=\u00bbMontserrat|700|||||||\u00bb header_4_text_color=\u00bb#0F1154&#8243; header_4_font_size=\u00bb28px\u00bb header_4_line_height=\u00bb1.6em\u00bb header_5_font=\u00bbMontserrat|700|||||||\u00bb header_5_text_color=\u00bb#0F1154&#8243; header_5_font_size=\u00bb18px\u00bb header_5_line_height=\u00bb150%\u00bb header_6_font=\u00bbMontserrat||||||||\u00bb header_6_text_color=\u00bb#0F1154&#8243; custom_margin=\u00bb||||false|false\u00bb custom_margin_tablet=\u00bb5vw||0px||false|false\u00bb custom_margin_phone=\u00bb5vw||0px||false|false\u00bb custom_margin_last_edited=\u00bbon|tablet\u00bb text_font_size_tablet=\u00bb\u00bb text_font_size_phone=\u00bb14px\u00bb text_font_size_last_edited=\u00bbon|phone\u00bb header_font_size_tablet=\u00bb40px\u00bb header_font_size_phone=\u00bb24px\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb header_2_font_size_tablet=\u00bb30px\u00bb header_2_font_size_phone=\u00bb20px\u00bb header_2_font_size_last_edited=\u00bbon|tablet\u00bb header_3_font_size_tablet=\u00bb20px\u00bb header_3_font_size_phone=\u00bb16px\u00bb header_3_font_size_last_edited=\u00bbon|tablet\u00bb header_4_font_size_tablet=\u00bb22px\u00bb header_4_font_size_phone=\u00bb16px\u00bb header_4_font_size_last_edited=\u00bbon|phone\u00bb header_5_font_size_tablet=\u00bb16px\u00bb header_5_font_size_phone=\u00bb14px\u00bb header_5_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>Suscr\u00edbete a las notificaciones<\/h3>\n<p>[\/et_pb_text][et_pb_signup mailchimp_list=\u00bbjohnmed11|4df712ed92&#8243; first_name_field=\u00bboff\u00bb last_name_field=\u00bboff\u00bb button_text=\u00bbSin cuotas\u00bb _builder_version=\u00bb4.17.3&#8243; _module_preset=\u00bbdefault\u00bb form_field_background_color=\u00bbRGBA(255,255,255,0)\u00bb form_field_text_color=\u00bb#E5E5E5&#8243; form_field_font=\u00bbRoboto||||||||\u00bb form_field_font_size=\u00bb18px\u00bb use_background_color=\u00bboff\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb18px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb0px\u00bb button_border_radius=\u00bb0px\u00bb button_font=\u00bbRoboto|500|||||||\u00bb button_use_icon=\u00bboff\u00bb button_custom_padding=\u00bb15px||15px||true|false\u00bb form_field_font_size_tablet=\u00bb18px\u00bb form_field_font_size_phone=\u00bb14px\u00bb form_field_font_size_last_edited=\u00bbon|phone\u00bb button_text_size_tablet=\u00bb18px\u00bb button_text_size_phone=\u00bb14px\u00bb button_text_size_last_edited=\u00bbon|phone\u00bb border_radii_fields=\u00bbon|0px|0px|0px|0px\u00bb border_width_all_fields=\u00bb2px\u00bb border_color_all_fields=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_signup][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PublicacionesNotasInformesAn\u00e1lisisMedioslinkedinSuscr\u00edbete a las notificaciones<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-280","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/pages\/280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/comments?post=280"}],"version-history":[{"count":25,"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/pages\/280\/revisions"}],"predecessor-version":[{"id":1124,"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/pages\/280\/revisions\/1124"}],"wp:attachment":[{"href":"https:\/\/evolutio-ci.com\/index.php\/wp-json\/wp\/v2\/media?parent=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}